{"id":205333,"date":"2023-07-04T16:02:25","date_gmt":"2023-07-04T14:02:25","guid":{"rendered":"https:\/\/www.sma-sunny.com\/?p=205333"},"modified":"2023-07-04T16:02:25","modified_gmt":"2023-07-04T14:02:25","slug":"a-magia-da-festa-junina-na-sma-brasil","status":"publish","type":"post","link":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/","title":{"rendered":"A magia da Festa Junina na SMA Brasil!"},"content":{"rendered":"<p><strong>O time da SMA Brasil se reuniu para comemorar as Festas Juninas. Tiramos um momento nas nossas rotinas de trabalho para descontra\u00e7\u00e3o e integra\u00e7\u00e3o entre a equipe, celebrando a cultura e as tradi\u00e7\u00f5es brasileiras.<\/strong><\/p>\n<p>A Festa Junina, \u00e9 uma celebra\u00e7\u00e3o tradicional brasileira realizada em junho para homenagear S\u00e3o Jo\u00e3o Batista. \u00c9 uma das festas mais populares e vibrantes do Brasil, principalmente na regi\u00e3o Nordeste do pa\u00eds, e seguida por todas as regi\u00f5es!<\/p>\n<p>A SMA entende a import\u00e2ncia de promover eventos que fortale\u00e7am os la\u00e7os entre os membros da equipe, e esta Festa \u00e9 uma oportunidade perfeita para isso. Ao organizar essa comemora\u00e7\u00e3o, criamos um ambiente descontra\u00eddo e acolhedor, que permite que todos se divirtam e se aproximem de forma mais informal.<\/p>\n<p>Semana passada fizemos a nossa festa. Viemos prontos com nossas camisas xadrez, soltamos a criatividade nos trajes caipiras e entramos no clima dessa festan\u00e7a. Saboreamos as comidas t\u00edpicas como o arroz-doce, canjica, pipoca, past\u00e9is, bolos de milho e de pa\u00e7oca e ao som das m\u00fasicas tradicionais e muita anima\u00e7\u00e3o. Todos entraram no clima desta festa encantadora. Celebramos o final primeiro semestre do ano e renovamos as energias para come\u00e7ar o segundo semestre com muitas expectativas que deixaram a festa ainda mais animada!<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;205333&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;1&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 voto)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;A magia da Festa Junina na SMA Brasil!&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n<div class='printomatic pom-default ' id='id4822'  data-print_target='article'><\/div>","protected":false},"excerpt":{"rendered":"<p>O time da SMA Brasil se reuniu para comemorar as Festas Juninas. Tiramos um momento nas nossas rotinas de trabalho para descontra\u00e7\u00e3o e integra\u00e7\u00e3o entre a equipe, celebrando a cultura e as tradi\u00e7\u00f5es brasileiras.<\/p>\n","protected":false},"author":149,"featured_media":205334,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2038],"tags":[],"class_list":["post-205333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A magia da Festa Junina na SMA Brasil! - Sunny. SMA Corporate Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A magia da Festa Junina na SMA Brasil! - Sunny. SMA Corporate Blog\" \/>\n<meta property=\"og:description\" content=\"O time da SMA Brasil se reuniu para comemorar as Festas Juninas. Tiramos um momento nas nossas rotinas de trabalho para descontra\u00e7\u00e3o e integra\u00e7\u00e3o entre a equipe, celebrando a cultura e as tradi\u00e7\u00f5es brasileiras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunny. SMA Corporate Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/SMASolarTechnology\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-04T14:02:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SMA Brasil\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:site\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SMA Brasil\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/\",\"url\":\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/\",\"name\":\"A magia da Festa Junina na SMA Brasil! - Sunny. SMA Corporate Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg\",\"datePublished\":\"2023-07-04T14:02:25+00:00\",\"dateModified\":\"2023-07-04T14:02:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/#\/schema\/person\/a80643835dff94a1f44053cb2034786a\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#primaryimage\",\"url\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg\",\"contentUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg\",\"width\":1400,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.sma-sunny.com\/pt-br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A magia da Festa Junina na SMA Brasil!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/#website\",\"url\":\"https:\/\/www.sma-sunny.com\/pt-br\/\",\"name\":\"Sunny. SMA Corporate Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sma-sunny.com\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/#\/schema\/person\/a80643835dff94a1f44053cb2034786a\",\"name\":\"SMA Brasil\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.sma-sunny.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b32f8148a83599f750fdcb79ce9e98204279e983e284b367d7d561a6b3456d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b32f8148a83599f750fdcb79ce9e98204279e983e284b367d7d561a6b3456d6?s=96&d=mm&r=g\",\"caption\":\"SMA Brasil\"},\"url\":\"https:\/\/www.sma-sunny.com\/pt-br\/author\/sma-brasil\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A magia da Festa Junina na SMA Brasil! - Sunny. SMA Corporate Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/","og_locale":"pt_BR","og_type":"article","og_title":"A magia da Festa Junina na SMA Brasil! - Sunny. SMA Corporate Blog","og_description":"O time da SMA Brasil se reuniu para comemorar as Festas Juninas. Tiramos um momento nas nossas rotinas de trabalho para descontra\u00e7\u00e3o e integra\u00e7\u00e3o entre a equipe, celebrando a cultura e as tradi\u00e7\u00f5es brasileiras.","og_url":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/","og_site_name":"Sunny. SMA Corporate Blog","article_publisher":"https:\/\/facebook.com\/SMASolarTechnology","article_published_time":"2023-07-04T14:02:25+00:00","og_image":[{"width":1400,"height":676,"url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg","type":"image\/jpeg"}],"author":"SMA Brasil","twitter_card":"summary_large_image","twitter_creator":"@SMAsolar","twitter_site":"@SMAsolar","twitter_misc":{"Escrito por":"SMA Brasil","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/","url":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/","name":"A magia da Festa Junina na SMA Brasil! - Sunny. SMA Corporate Blog","isPartOf":{"@id":"https:\/\/www.sma-sunny.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#primaryimage"},"image":{"@id":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg","datePublished":"2023-07-04T14:02:25+00:00","dateModified":"2023-07-04T14:02:25+00:00","author":{"@id":"https:\/\/www.sma-sunny.com\/pt-br\/#\/schema\/person\/a80643835dff94a1f44053cb2034786a"},"breadcrumb":{"@id":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#primaryimage","url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg","contentUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2023\/07\/Festa-Junina-header.jpg","width":1400,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/www.sma-sunny.com\/pt-br\/a-magia-da-festa-junina-na-sma-brasil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sma-sunny.com\/pt-br\/"},{"@type":"ListItem","position":2,"name":"A magia da Festa Junina na SMA Brasil!"}]},{"@type":"WebSite","@id":"https:\/\/www.sma-sunny.com\/pt-br\/#website","url":"https:\/\/www.sma-sunny.com\/pt-br\/","name":"Sunny. SMA Corporate Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sma-sunny.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.sma-sunny.com\/pt-br\/#\/schema\/person\/a80643835dff94a1f44053cb2034786a","name":"SMA Brasil","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.sma-sunny.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b32f8148a83599f750fdcb79ce9e98204279e983e284b367d7d561a6b3456d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b32f8148a83599f750fdcb79ce9e98204279e983e284b367d7d561a6b3456d6?s=96&d=mm&r=g","caption":"SMA Brasil"},"url":"https:\/\/www.sma-sunny.com\/pt-br\/author\/sma-brasil\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/posts\/205333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/users\/149"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/comments?post=205333"}],"version-history":[{"count":0,"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/posts\/205333\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/media\/205334"}],"wp:attachment":[{"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/media?parent=205333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/categories?post=205333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/pt-br\/wp-json\/wp\/v2\/tags?post=205333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}