{"id":137891,"date":"2021-10-14T10:36:39","date_gmt":"2021-10-14T08:36:39","guid":{"rendered":"https:\/\/sma-sunny.com\/?p=137891"},"modified":"2021-10-14T10:37:07","modified_gmt":"2021-10-14T08:37:07","slug":"gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs","status":"publish","type":"post","link":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/","title":{"rendered":"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs"},"content":{"rendered":"<p>Entre les rendez-vous commerciaux, le dimensionnement et la mise en service des installations photovolta\u00efques, votre agenda est d\u00e9j\u00e0 surcharg\u00e9. Si l\u2019on ajoute \u00e0 cela les pannes impr\u00e9vues n\u00e9c\u00e9ssitant des interventions de maintenance&#8230;organiser votre quotidien devient un v\u00e9ritable challenge!<\/p>\n<p>Et si nous vous disions qu\u2019il existe des onduleurs suffisamment intelligents pour surveiller leurs propres signes vitaux, savoir quand quelque chose d&rsquo;irr\u00e9gulier se produit et appeler \u00e0 l&rsquo;aide tous seuls ?<\/p>\n<h2>SMA Smart Connected : Quels avantages pour les installateurs ?<\/h2>\n<p>La gamme d\u2019onduleurs SMA b\u00e9n\u00e9ficie d\u2019un service de surveillance int\u00e9gr\u00e9 gratuit : SMA Smart Connected. Gr\u00e2ce \u00e0 cette solution, vous r\u00e9duisez les co\u00fbts li\u00e9s aux interventions de maintenance, tout en am\u00e9liorant la s\u00e9curit\u00e9 et la productivit\u00e9 de l\u2019installation photovolta\u00efque pour les propri\u00e9taires. Le tout, sans d\u00e9pense suppl\u00e9mentaire.<\/p>\n<p>Cette solution gratuite est int\u00e9gr\u00e9e \u00e0 tous les onduleurs SMA des gammes Sunny Boy, Sunny Boy Storage et Sunny Tripower. Chaque mois, un rapport de performance est \u00e9dit\u00e9 et vous est envoy\u00e9, de m\u00eame qu\u2019au propri\u00e9taire de l\u2019installation.<\/p>\n<p>En plus de ce rapport mensuel, Smart Connected d\u00e9tecte intantan\u00e9ment les probl\u00e8mes du syst\u00e8me, vous envoi un rapport d\u2019erreur par email et lance le processus de r\u00e9paration et de remplacement si n\u00e9cessaire.Non seulement vous n&rsquo;avez plus besoin de vous rendre sur place une premi\u00e8re fois pour constater qu&rsquo;un onduleur doit \u00eatre remplac\u00e9, puis de revenir une fois que l&rsquo;onduleur est exp\u00e9di\u00e9 sur le site, mais vous pouvez plus facilement organiser avec vos clients le rendez-vous pour remplacer l&rsquo;onduleur. Si vous savez que vous serez dans la r\u00e9gion la semaine suivante, vous pouvez programmer le remplacement de l&rsquo;onduleur \u00e0 ce moment-l\u00e0. Ainsi, vos co\u00fbts de service li\u00e9s aux d\u00e9placements seront r\u00e9duits de plus de moiti\u00e9 et votre client \u00e9vite une baisse de production caus\u00e9e par des temps d\u2019arr\u00eat trop longs.<\/p>\n<h2>Comment activer SMA Smart Connected lors de la mise en service ?<\/h2>\n<p>Vous pouvez activer la fonction SMA Smart Connected d\u00e8s l\u2019enregistrement de l\u2019onduleur dans le syst\u00e8me de surveillance Sunny Portal, et dans un d\u00e9lai de 90 jours apr\u00e8s la mise en service.<\/p>\n<p>Une fois le service activ\u00e9, SMA Smart Connected commence \u00e0 surveiller de mani\u00e8re proactive les communications entre l\u2019installation et le portail. Toutes les alertes ou messages d\u2019erreur envoy\u00e9s peuvent \u00eatre analys\u00e9s par les techniciens SMA, leur permettant de fournir une assistance sur mesure : des conseils de d\u00e9pannage par e-mail jusqu\u2019\u00e0 l\u2019envoi proactif d\u2019un appareil de remplacement.<\/p>\n<p>Regardez la minute photovolta\u00efque anim\u00e9e par Serge Communal, formateur de la SMA Solar Academy,pour plus d\u2019information technique sur SMA Smart Connected.<\/p>\n<div  class='avia-video av-av_video-2bcaeb08b6b62a95a676bc4c170a309c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/www.youtube.com\/watch?v=VT6qT3Yiwvs'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe title=\"La minute photovolta\u00efque : SMA Smart Connected\" width=\"1500\" height=\"844\" data-src=\"https:\/\/www.youtube.com\/embed\/VT6qT3Yiwvs?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div>\n<div  class='av_promobox av-av_promobox-6bdac236d5de4b527c724c6f30d180fb avia-button-no  avia-builder-el-1  el_after_av_video  avia-builder-el-last '><div class='avia-promocontent'><p>Vous \u00eates installateur photovolta\u00efque ?<br \/>\nAlors rejoignez la communaut\u00e9 des installateurs SMA en France\u00a0pour b\u00e9n\u00e9ficier d\u2019informations d\u00e9di\u00e9es au d\u00e9veloppement de votre activit\u00e9 et d\u2019\u00e9changes entre professionnels tout au long de l\u2019ann\u00e9e.<\/p>\n<p><a href=\"https:\/\/sma-sunny.com\/wp-content\/uploads\/2021\/07\/Vous-etes-installateur-photovoltaique-.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-135685 lazyload\" data-src=\"https:\/\/sma-sunny.com\/wp-content\/uploads\/2021\/07\/Vous-etes-installateur-photovoltaique-.jpg\" alt=\"\" width=\"1024\" height=\"293\" data-srcset=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/Vous-etes-installateur-photovoltaique-.jpg 1024w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/Vous-etes-installateur-photovoltaique--262x75.jpg 262w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/Vous-etes-installateur-photovoltaique--768x220.jpg 768w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/Vous-etes-installateur-photovoltaique--450x129.jpg 450w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/293;\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.sma-france.com\/partenariat\/communaute-des-installateurs-sma.html?utm_source=blog&amp;utm_medium=referral&amp;utm_campaign=articlemyth1\" target=\"_blank\" rel=\"noopener\">&gt; Je rejoins la communaut\u00e9 d\u2019installateurs SMA<\/a><\/p>\n<\/div><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;137891&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;1&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 vote)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n<div class='printomatic pom-default ' id='id7615'  data-print_target='article'><\/div>","protected":false},"excerpt":{"rendered":"<p>Entre les rendez-vous commerciaux, le dimensionnement et la mise en service des installations photovolta\u00efques, votre agenda est d\u00e9j\u00e0 surcharg\u00e9. Si l\u2019on ajoute \u00e0 cela les pannes impr\u00e9vues n\u00e9c\u00e9ssitant des interventions de maintenance&#8230;organiser votre quotidien devient un v\u00e9ritable challenge!<br \/>\nEt si nous vous disions qu\u2019il existe des onduleurs suffisamment intelligents pour surveiller leurs propres signes vitaux, savoir quand quelque chose d&rsquo;irr\u00e9gulier se produit et appeler \u00e0 l&rsquo;aide tous seuls ?<\/p>\n","protected":false},"author":117,"featured_media":137894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-137891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solutions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs - Sunny. SMA Corporate Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs - Sunny. SMA Corporate Blog\" \/>\n<meta property=\"og:description\" content=\"Entre les rendez-vous commerciaux, le dimensionnement et la mise en service des installations photovolta\u00efques, votre agenda est d\u00e9j\u00e0 surcharg\u00e9. Si l\u2019on ajoute \u00e0 cela les pannes impr\u00e9vues n\u00e9c\u00e9ssitant des interventions de maintenance...organiser votre quotidien devient un v\u00e9ritable challenge! Et si nous vous disions qu\u2019il existe des onduleurs suffisamment intelligents pour surveiller leurs propres signes vitaux, savoir quand quelque chose d&#039;irr\u00e9gulier se produit et appeler \u00e0 l&#039;aide tous seuls ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunny. SMA Corporate Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/SMASolarTechnology\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T08:36:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-14T08:37:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"791\" \/>\n\t<meta property=\"og:image:height\" content=\"229\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Margaux Canales\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:site\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Margaux Canales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/\",\"name\":\"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs - Sunny. SMA Corporate Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg\",\"datePublished\":\"2021-10-14T08:36:39+00:00\",\"dateModified\":\"2021-10-14T08:37:07+00:00\",\"author\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/c7781d7c0dec18d7888640fe84928262\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#primaryimage\",\"url\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg\",\"contentUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg\",\"width\":791,\"height\":229,\"caption\":\"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.sma-sunny.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#website\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/\",\"name\":\"Sunny. SMA Corporate Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sma-sunny.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/c7781d7c0dec18d7888640fe84928262\",\"name\":\"Margaux Canales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/margaux-120x120.jpg\",\"contentUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/margaux-120x120.jpg\",\"caption\":\"Margaux Canales\"},\"url\":\"https:\/\/www.sma-sunny.com\/fr\/author\/margaux-canales\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs - Sunny. SMA Corporate Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/","og_locale":"fr_FR","og_type":"article","og_title":"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs - Sunny. SMA Corporate Blog","og_description":"Entre les rendez-vous commerciaux, le dimensionnement et la mise en service des installations photovolta\u00efques, votre agenda est d\u00e9j\u00e0 surcharg\u00e9. Si l\u2019on ajoute \u00e0 cela les pannes impr\u00e9vues n\u00e9c\u00e9ssitant des interventions de maintenance...organiser votre quotidien devient un v\u00e9ritable challenge! Et si nous vous disions qu\u2019il existe des onduleurs suffisamment intelligents pour surveiller leurs propres signes vitaux, savoir quand quelque chose d'irr\u00e9gulier se produit et appeler \u00e0 l'aide tous seuls ?","og_url":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/","og_site_name":"Sunny. SMA Corporate Blog","article_publisher":"https:\/\/facebook.com\/SMASolarTechnology","article_published_time":"2021-10-14T08:36:39+00:00","article_modified_time":"2021-10-14T08:37:07+00:00","og_image":[{"width":791,"height":229,"url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg","type":"image\/jpeg"}],"author":"Margaux Canales","twitter_card":"summary_large_image","twitter_creator":"@SMAsolar","twitter_site":"@SMAsolar","twitter_misc":{"\u00c9crit par":"Margaux Canales","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/","url":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/","name":"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs - Sunny. SMA Corporate Blog","isPartOf":{"@id":"https:\/\/www.sma-sunny.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#primaryimage"},"image":{"@id":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg","datePublished":"2021-10-14T08:36:39+00:00","dateModified":"2021-10-14T08:37:07+00:00","author":{"@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/c7781d7c0dec18d7888640fe84928262"},"breadcrumb":{"@id":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#primaryimage","url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg","contentUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/10\/header_blog_fr.jpg","width":791,"height":229,"caption":"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sma-sunny.com\/fr\/gagnez-du-temps-sur-la-maintenance-des-installations-pv-grace-a-un-service-de-surveillance-integre-aux-onduleurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sma-sunny.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Gagnez du temps sur la maintenance des installations PV gr\u00e2ce \u00e0 un service de surveillance int\u00e9gr\u00e9 aux onduleurs"}]},{"@type":"WebSite","@id":"https:\/\/www.sma-sunny.com\/fr\/#website","url":"https:\/\/www.sma-sunny.com\/fr\/","name":"Sunny. SMA Corporate Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sma-sunny.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/c7781d7c0dec18d7888640fe84928262","name":"Margaux Canales","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/margaux-120x120.jpg","contentUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/07\/margaux-120x120.jpg","caption":"Margaux Canales"},"url":"https:\/\/www.sma-sunny.com\/fr\/author\/margaux-canales\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts\/137891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/users\/117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/comments?post=137891"}],"version-history":[{"count":0,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts\/137891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/media\/137894"}],"wp:attachment":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/media?parent=137891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/categories?post=137891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/tags?post=137891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}