{"id":131718,"date":"2021-03-09T02:38:45","date_gmt":"2021-03-09T01:38:45","guid":{"rendered":"https:\/\/www.sma-sunny.com\/top-4-reasons-to-register-your-plant-to-sunny-portal\/"},"modified":"2021-03-19T08:35:16","modified_gmt":"2021-03-19T07:35:16","slug":"sunny-portal-4-raisons-denregistrer-vos-installations","status":"publish","type":"post","link":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/","title":{"rendered":"Sunny Portal\u00a0: 4 raisons d&rsquo;enregistrer vos installations"},"content":{"rendered":"<p><strong>Avec plus de 330 000 installations enregistr\u00e9es dans plus de 160 pays \u00e0 travers le monde, le SMA Sunny Portal est le plus grand portail de surveillance PV au monde. Au-del\u00e0 de la surveillance, il existe de nombreuses raisons d\u2019enregistrer ses installations sur la plateforme. Mike Mahon, formateur \u00e0 la Solar Academy de SMA America, nous en pr\u00e9sente quatre dans cet article.<\/strong><\/p>\n<h2><strong>1)<\/strong> Acc\u00e8s \u00e0 Smart Connected<\/h2>\n<p><img decoding=\"async\" class=\"alignright size-medium wp-image-131454 lazyload\" data-src=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Smart-Connected-262x149.jpg\" alt=\"SMA Service\" width=\"262\" height=\"149\" data-srcset=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Smart-Connected-262x149.jpg 262w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Smart-Connected-1024x582.jpg 1024w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Smart-Connected-768x437.jpg 768w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Smart-Connected-450x256.jpg 450w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Smart-Connected.jpg 1187w\" data-sizes=\"(max-width: 262px) 100vw, 262px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 262px; --smush-placeholder-aspect-ratio: 262\/149;\" \/>L&rsquo;enregistrement d&rsquo;une installation sur Sunny Portal permet l&rsquo;acc\u00e8s \u00e0 SMA Smart Connected, service de surveillance automatique et gratuit de l\u2019onduleur par SMA. Une fois le service activ\u00e9, SMA commence \u00e0 surveiller de mani\u00e8re proactive les communications entre l&rsquo;installation et le portail. Toutes les alertes ou messages d&rsquo;erreur envoy\u00e9s peuvent \u00eatre analys\u00e9s par les techniciens SMA leur permettant de fournir une assistance sur mesure\u00a0: des conseils de d\u00e9pannage par e-mail jusqu&rsquo;\u00e0 l&rsquo;envoi proactif d&rsquo;un appareil de remplacement \u2013 et ce, avant m\u00eame que l&rsquo;installateur ne se rende sur place ! Afin de limiter autant que possible les d\u00e9placements sur site des installateurs en cette p\u00e9riode exceptionnelle, SMA a d\u00e9cid\u00e9 d\u2019\u00e9tendre la p\u00e9riode d\u2019activation de SMA Smart Connected jusqu&rsquo;\u00e0 2 ans apr\u00e8s la mise en service de l&rsquo;onduleur (contre 90 jours habituellement). Pour en savoir plus sur Smart Connected, <a href=\"https:\/\/www.sma.de\/fr\/produits\/surveillance-controle\/sma-smart-connected.html\" target=\"_blank\" rel=\"noopener\">cliquez ici<\/a>.<\/p>\n<h2><strong>2) Mises \u00e0 jour automatiques du micrologiciel (\u00ab firmware \u00bb)<\/strong><\/h2>\n<p>Vous redoutez l&rsquo;id\u00e9e de vous rendre sur place pour mettre \u00e0 jour manuellement le firmware des appareils ? Moi aussi, c&rsquo;est pourquoi il est recommand\u00e9 de configurer les mises \u00e0 jour automatiques du firmware des appareils SMA lors de l&rsquo;enregistrement sur le Sunny Portal. Avec cette option, vous pouvez \u00eatre s\u00fbr que vos appareils SMA re\u00e7oivent les derni\u00e8res mises \u00e0 jour d\u00e8s qu&rsquo;elles sont disponibles !<\/p>\n<h2><strong>3) Envoi automatique de rapports de performance<\/strong><\/h2>\n<p>Vos clients souhaitent recevoir des informations sur la production de leur syst\u00e8me de mani\u00e8re r\u00e9guli\u00e8re sans se rendre sur SunnyPortal.com ? Il est tr\u00e8s facile de mettre en place des rapports automatiques pour les installations enregistr\u00e9es sur le Sunny Portal\u00a0: il vous suffit de configurer l\u2019envoi automatique de rapports de production quotidiens, hebdomadaires ou mensuels au propri\u00e9taire de l&rsquo;installation. Vous pouvez \u00e9galement faire envoyer des rapports automatiques d\u2019alertes ou d&rsquo;erreur au technicien de service concern\u00e9. Ne vous inqui\u00e9tez pas, vous pouvez ignorer les rapports des jours o\u00f9 il n&rsquo;y a pas de messages. Gr\u00e2ce \u00e0 cette fonctionnalit\u00e9, toutes les parties prenantes sont inform\u00e9es des performances de l&rsquo;installation.<\/p>\n<h2><strong>4) Analyse Pro<\/strong><\/h2>\n<p>(Fonctionnalit\u00e9 disponible uniquement via le Sunny Portal powered by ennexOS\u00a0: am\u00e9lioration de la fonction de graphique personnalis\u00e9 disponible sur le Sunny Portal classique). En quelques clics seulement, un historique des valeurs de toutes les variables de l&rsquo;installation peut \u00eatre repr\u00e9sent\u00e9 graphiquement et analys\u00e9. C&rsquo;est un gain de temps pour \u00e9tudier les performances et diagnostiquer les comportements inhabituels.<\/p>\n<div id=\"attachment_131443\" style=\"width: 1034px\" class=\"wp-caption alignnone\"><img decoding=\"async\" aria-describedby=\"caption-attachment-131443\" class=\"wp-image-131443 size-large lazyload\" data-src=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/SunnyPortal_BlogArticle_Screenshot_FR.png\" alt=\"Screenshot SMA Sunny Portal\" width=\"1024\" height=\"604\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/604;\" \/><p id=\"caption-attachment-131443\" class=\"wp-caption-text\">Exemple d&rsquo;Analyse Pro utilis\u00e9 pour \u00e9tudier le comportement d&rsquo;un Sunny Boy 7.7-US-41<\/p><\/div>\n<p>Cette image montre un graphique avec la puissance DC pour deux canaux d&rsquo;un onduleur Sunny Boy US-41 ainsi que la puissance AC de l&rsquo;appareil et la puissance totale de l&rsquo;installation &#8211; accessible en quelques clics seulement. Notez que les variables avec diff\u00e9rentes unit\u00e9s peuvent facilement \u00eatre repr\u00e9sent\u00e9es sur le m\u00eame graphique &#8211; des axes suppl\u00e9mentaires peuvent \u00eatre ajout\u00e9s si n\u00e9cessaire. Astuce : cliquez sur <i>D\u00e9tails<\/i> sous le graphique pour faire appara\u00eetre le bouton T\u00e9l\u00e9charger qui permet d&rsquo;exporter les donn\u00e9es affich\u00e9es dans le graphique actuel.<\/p>\n<p>Voici selon moi 4 bonnes raisons d\u2019enregistrer vos installations dans le Sunny Portal. Quelles sont les v\u00f4tres ? S&rsquo;il y a des fonctionnalit\u00e9s que vous aimeriez voir ajout\u00e9es \u00e0 l&rsquo;avenir, faites-le savoir \u00e0 SMA via la section Commentaires.<\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;131718&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;4&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;2.7&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;1&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;2.7\\\/5 - (4 votes)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Sunny Portal\u00a0: 4 raisons d\\u0026#039;enregistrer vos installations&quot;,&quot;width&quot;:&quot;61.6&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 61.6px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            2.7\/5 - (4 votes)    <\/div>\n    <\/div>\n<div class='printomatic pom-default ' id='id5873'  data-print_target='article'><\/div>","protected":false},"excerpt":{"rendered":"<p>Avec plus de 330 000 installations enregistr\u00e9es dans plus de 160 pays \u00e0 travers le monde, le SMA Sunny Portal&#8230;<\/p>\n","protected":false},"author":100,"featured_media":131436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[57],"tags":[],"class_list":["post-131718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-solutions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sunny Portal\u00a0: 4 raisons d&#039;enregistrer vos installations - Sunny. SMA Corporate Blog<\/title>\n<meta name=\"description\" content=\"SMA America Solar Academy Trainer Mike Mahon outlines his top four reasons why you should register your system in SMA Sunny Portal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sunny Portal\u00a0: 4 raisons d&#039;enregistrer vos installations - Sunny. SMA Corporate Blog\" \/>\n<meta property=\"og:description\" content=\"SMA America Solar Academy Trainer Mike Mahon outlines his top four reasons why you should register your system in SMA Sunny Portal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunny. SMA Corporate Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/SMASolarTechnology\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-09T01:38:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-19T07:35:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mike\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:site\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/\",\"name\":\"Sunny Portal\u00a0: 4 raisons d'enregistrer vos installations - Sunny. SMA Corporate Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg\",\"datePublished\":\"2021-03-09T01:38:45+00:00\",\"dateModified\":\"2021-03-19T07:35:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/543704762da4978ac85cb412aca21b87\"},\"description\":\"SMA America Solar Academy Trainer Mike Mahon outlines his top four reasons why you should register your system in SMA Sunny Portal.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#primaryimage\",\"url\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg\",\"contentUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg\",\"width\":1920,\"height\":760,\"caption\":\"SMA Sunny Portal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.sma-sunny.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sunny Portal\u00a0: 4 raisons d&rsquo;enregistrer vos installations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#website\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/\",\"name\":\"Sunny. SMA Corporate Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sma-sunny.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/543704762da4978ac85cb412aca21b87\",\"name\":\"Mike\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Mike-Mahon-120x120.jpg\",\"contentUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Mike-Mahon-120x120.jpg\",\"caption\":\"Mike\"},\"description\":\"Senior Technical Trainer, Solar Academy, SMA America. Mike hosts webinars and in-person trainings on SMA America\u2019s string inverters, communication products and design tools.\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/author\/mike\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sunny Portal\u00a0: 4 raisons d'enregistrer vos installations - Sunny. SMA Corporate Blog","description":"SMA America Solar Academy Trainer Mike Mahon outlines his top four reasons why you should register your system in SMA Sunny Portal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/","og_locale":"fr_FR","og_type":"article","og_title":"Sunny Portal\u00a0: 4 raisons d'enregistrer vos installations - Sunny. SMA Corporate Blog","og_description":"SMA America Solar Academy Trainer Mike Mahon outlines his top four reasons why you should register your system in SMA Sunny Portal.","og_url":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/","og_site_name":"Sunny. SMA Corporate Blog","article_publisher":"https:\/\/facebook.com\/SMASolarTechnology","article_published_time":"2021-03-09T01:38:45+00:00","article_modified_time":"2021-03-19T07:35:16+00:00","og_image":[{"width":1920,"height":760,"url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg","type":"image\/jpeg"}],"author":"Mike","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg","twitter_creator":"@SMAsolar","twitter_site":"@SMAsolar","twitter_misc":{"\u00c9crit par":"Mike","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/","url":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/","name":"Sunny Portal\u00a0: 4 raisons d'enregistrer vos installations - Sunny. SMA Corporate Blog","isPartOf":{"@id":"https:\/\/www.sma-sunny.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#primaryimage"},"image":{"@id":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg","datePublished":"2021-03-09T01:38:45+00:00","dateModified":"2021-03-19T07:35:16+00:00","author":{"@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/543704762da4978ac85cb412aca21b87"},"description":"SMA America Solar Academy Trainer Mike Mahon outlines his top four reasons why you should register your system in SMA Sunny Portal.","breadcrumb":{"@id":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#primaryimage","url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg","contentUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Sunny-Portal-ennexOS.jpg","width":1920,"height":760,"caption":"SMA Sunny Portal"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sma-sunny.com\/fr\/sunny-portal-4-raisons-denregistrer-vos-installations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sma-sunny.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sunny Portal\u00a0: 4 raisons d&rsquo;enregistrer vos installations"}]},{"@type":"WebSite","@id":"https:\/\/www.sma-sunny.com\/fr\/#website","url":"https:\/\/www.sma-sunny.com\/fr\/","name":"Sunny. SMA Corporate Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sma-sunny.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/543704762da4978ac85cb412aca21b87","name":"Mike","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Mike-Mahon-120x120.jpg","contentUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2021\/03\/Mike-Mahon-120x120.jpg","caption":"Mike"},"description":"Senior Technical Trainer, Solar Academy, SMA America. Mike hosts webinars and in-person trainings on SMA America\u2019s string inverters, communication products and design tools.","url":"https:\/\/www.sma-sunny.com\/fr\/author\/mike\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts\/131718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/comments?post=131718"}],"version-history":[{"count":0,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts\/131718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/media\/131436"}],"wp:attachment":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/media?parent=131718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/categories?post=131718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/tags?post=131718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}