{"id":111297,"date":"2020-05-07T14:45:16","date_gmt":"2020-05-07T12:45:16","guid":{"rendered":"https:\/\/www.sma-sunny.com\/pv-moduloptimierer-so-ueberfluessig-wie-kuehlschraenke-am-nordpol\/"},"modified":"2021-06-07T09:13:10","modified_gmt":"2021-06-07T07:13:10","slug":"pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol","status":"publish","type":"post","link":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/","title":{"rendered":"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f"},"content":{"rendered":"<p><strong>#Optimiser la production \u00e9nerg\u00e9tique des modules PV de mani\u00e8re intelligente et s\u00fbre \u00e0 la fois. Ajout de composants \u00e9lectroniques ou solution int\u00e9gr\u00e9e\u202f? En quoi les optimiseurs de modules peuvent constituer un risque pour la s\u00e9curit\u00e9\u202f? Et comment les op\u00e9rateurs et les installateurs peuvent-ils b\u00e9n\u00e9ficier d\u2019une efficacit\u00e9 et d\u2019une s\u00e9curit\u00e9 accrues gr\u00e2ce au logiciel int\u00e9gr\u00e9 SMA ShadeFix\u202f? Hannes Knopf, Expert en technologies d\u2019onduleurs strings, partage ses connaissances sur le sujet.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Une \u00e9tude a compar\u00e9 diff\u00e9rentes technologies d\u2019optimisation de la production de modules PV. La solution logicielle SMA ShadeFix s\u2019est av\u00e9r\u00e9e plus efficace que les solutions mat\u00e9rielles MLPE (Module Level Power Electronics). Comment expliquer un tel r\u00e9sultat\u202f? <\/strong><\/p>\n<p>La particularit\u00e9 des onduleurs strings SMA est l\u2019int\u00e9gration de la technologie d\u2019optimisation SMA ShadeFix. Cette derni\u00e8re permet aux installations PV de convertir automatiquement le rayonnement lumineux du soleil en courant alternatif et ce, m\u00eame en cas d\u2019ombrage. Je suis particuli\u00e8rement ravi que cela ait \u00e9t\u00e9 confirm\u00e9 par une \u00e9tude scientifique. Elle d\u00e9montre que les solutions mat\u00e9rielles pour la gestion de l\u2019ombrage permettent d\u2019augmenter la production des modules PV que dans de rares situations, comme par exemple en cas d\u2019ombrage permanent tr\u00e8s important. Cependant, dans la majorit\u00e9 des installations PV, les optimiseurs sont aussi utiles qu\u2019un frigo au p\u00f4le Nord.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Produire de l\u2019\u00e9nergie \u00e0 l\u2019ombre. Cela semble paradoxal. Comment cela fonctionne-t-il\u202f? <\/strong><\/p>\n<p>A proprement parler, cela n\u2019est pas possible. Ou du moins, de fa\u00e7on n\u00e9gligeable. En revanche, dans le cas d\u2019installations PV, les modules PV ne sont ombrag\u00e9s que temporairement au cours d\u2019une journ\u00e9e, par exemple le matin ou le soir. Il s&rsquo;agit par exemple des ombres projet\u00e9es par une chemin\u00e9e, une lucarne ou encore un arbre. Et c\u2019est pr\u00e9cis\u00e9ment l\u00e0 que notre technologie prend tout son sens. Elle est con\u00e7ue pour garantir que l&rsquo;onduleur tire toujours la puissance maximale des modules PV, m\u00eame \u00e0 l&rsquo;ombre.<br \/>\nPour simplifier, on peut pr\u00e9senter les choses ainsi\u202f: la vitesse \u00e0 laquelle les \u00e9lectrons traversent cellules photovolta\u00efques des modules d\u00e9pend de l\u2019irradiation du soleil. Au soleil, ils se d\u00e9placent tr\u00e8s vite. A l\u2019inverse, ils sont plus lents \u00e0 l\u2019ombre. Cela cr\u00e9e une sorte d\u2019embouteillage d\u2019\u00e9lectrons dans la partie ombrag\u00e9e du module. SMA ShadeFix fait contourner la partie ombrag\u00e9e du module, qui ne produit de toute fa\u00e7on que peu d\u2019\u00e9nergie, et guide les \u00e9lectrons vers la partie expos\u00e9e. Ils peuvent alors se d\u00e9placer \u00e0 vitesse normale. Le r\u00e9sultat est sans appel\u202f: la production d\u2019\u00e9nergie est plus \u00e9lev\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii.png\"><img decoding=\"async\" class=\"alignnone wp-image-111300 size-full lazyload\" data-src=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii.png\" alt=\"SMA Shade Scenarii\" width=\"1580\" height=\"765\" data-srcset=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii.png 1580w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii-262x127.png 262w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii-1024x496.png 1024w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii-768x372.png 768w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii-1536x744.png 1536w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Shade_Scenarii-450x218.png 450w\" data-sizes=\"(max-width: 1580px) 100vw, 1580px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1580px; --smush-placeholder-aspect-ratio: 1580\/765;\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Certains pays exigent toujours l\u2019utilisation d\u2019optimiseurs sous pr\u00e9texte que l\u2019ajout de composants \u00e9lectroniques augmenterait la s\u00e9curit\u00e9 des syst\u00e8mes. <\/strong><\/p>\n<p>L\u2019usage des MPLE pour l\u2019isolation au niveau des modules, appel\u00e9 dispositif d\u2019arr\u00eat rapide, est pertinent pour la s\u00e9curit\u00e9 du personnel d\u2019urgence tels que les pompiers. Mais c\u2019est compl\u00e8tement oublier celle des installateurs. Les r\u00e8gles d\u2019arr\u00eat rapide aux \u00c9tats-Unis et la limitation de la tension \u00e0 80 volts peuvent mener \u00e0 une analyse incorrecte de la situation. 80 volts dans un module PV restent dangereux. Et qui peut s\u2019assurer que le dispositif d\u2019arr\u00eat rapide fonctionne encore apr\u00e8s 20 ans pass\u00e9s sur un toit ou en cas d\u2019incendie\u202f? De plus, un grand nombre de composants, surtout les connecteurs, augmentent le risque d\u2019incendie dans le syst\u00e8me et l\u2019arr\u00eat obligatoire ne fonctionne qu\u2019au niveau des modules. Le temps pass\u00e9 par les installateurs sur le toit se retrouve \u00e9galement fortement rallong\u00e9 et n\u2019est pas pris en compte. Ils s\u2019exposent pourtant \u00e0 plus de risques, comme par exemple celui de chutes de hauteur.<\/p>\n<p>Dans les pays o\u00f9 les fonctions d&rsquo;arr\u00eat au niveau des modules sont obligatoires, nous nous appuyons sur la norme SunSpec de signal d&rsquo;arr\u00eat rapide et donc sur des appareils et des composants certifi\u00e9s selon cette m\u00eame norme.<\/p>\n<p>Les convertisseurs de tension dans le circuit d&rsquo;alimentation de l&rsquo;\u00e9lectronique du module ne sont donc pas n\u00e9cessaires, ce qui r\u00e9duit de plus de moiti\u00e9 le nombre de composants sur le toit et am\u00e9liore donc la fiabilit\u00e9. Par cons\u00e9quent, la s\u00e9curit\u00e9 du personnel d\u2019urgence et des installateurs est am\u00e9lior\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pourquoi a-t-on toujours besoin d\u2019optimiseurs de modules aujourd\u2019hui\u202f? <\/strong><\/p>\n<p>Bonne question. Les r\u00e9sultats de l\u2019\u00e9tude sont sans appel. Plus d&rsquo;\u00e9lectronique sur le toit ne fait pas qu&rsquo;augmenter le travail d&rsquo;installation et la probabilit\u00e9 d&rsquo;erreurs. Cela signifie \u00e9galement un risque d&rsquo;accident plus \u00e9lev\u00e9 pour les installateurs, car ils doivent passer plus de temps sur le toit. De plus, un nombre plus \u00e9lev\u00e9 de composants, notamment les connecteurs, augmente le risque d&rsquo;incendie dans le syst\u00e8me. Les modules PV standard sont \u00e9quip\u00e9s de deux connecteurs DC. Chaque dispositif MLPE ajout\u00e9 introduit quatre connecteurs suppl\u00e9mentaires. Le fait de tripler les points de contact augmente les risques de d\u00e9faillance et d&rsquo;incendie. Les sources potentielles de danger sont notamment des connecteurs mal mont\u00e9s, des connexions l\u00e2ches et en particulier une non-compatibilit\u00e9, c&rsquo;est-\u00e0-dire des connecteurs de diff\u00e9rents fabricants.<\/p>\n<p>Si toutefois une partie du syst\u00e8me est fortement ombrag\u00e9e, l\u2019utilisation s\u00e9lective d\u2019un optimiseur peut \u00eatre justifi\u00e9e. Un installateur particuli\u00e8rement comp\u00e9tent est requis pour planifier le syst\u00e8me de mani\u00e8re efficace tout comme pour d\u00e9terminer si un module PV est vraiment utile \u00e0 l\u2019emplacement d\u00e9sir\u00e9. Il n\u2019existe encore aucune technologie permettant de transformer l\u2019ombre en lumi\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_111308\" style=\"width: 1371px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Plant_Example.png\"><img decoding=\"async\" aria-describedby=\"caption-attachment-111308\" class=\"wp-image-111308 size-full lazyload\" data-src=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Plant_Example.png\" alt=\"Example Plant SMA\" width=\"1361\" height=\"936\" data-srcset=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Plant_Example.png 1361w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Plant_Example-262x180.png 262w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Plant_Example-1024x704.png 1024w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Plant_Example-768x528.png 768w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/FR_Plant_Example-450x309.png 450w\" data-sizes=\"(max-width: 1361px) 100vw, 1361px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1361px; --smush-placeholder-aspect-ratio: 1361\/936;\" \/><\/a><p id=\"caption-attachment-111308\" class=\"wp-caption-text\">Comparaison des composants d\u2019une installation commerciale typique de 50\u202fkW\u202f: pr\u00e8s de 2000 composants \u00e9lectroniques sont n\u00e9cessaires dans la solution SMA contre 60\u202f000 pour les optimiseurs de module.<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Maximiser la production \u00e9nerg\u00e9tique pour les clients et la s\u00e9curit\u00e9 pour les techniciens. Comment les concepteurs de syst\u00e8mes peuvent-ils y parvenir\u202f? <\/strong><\/p>\n<p>La solution est une conception de syst\u00e8me aussi simple que possible. C\u2019est ce qui constitue la base d\u2019un syst\u00e8me PV qui assure \u00e0 la fois la s\u00e9curit\u00e9 de l\u2019environnement de travail et une production la plus \u00e9lev\u00e9e possible pour l\u2019utilisateur tout au long de la dur\u00e9e de vie de l\u2019installation. C\u2019est pour cela que nous int\u00e9grons directement les fonctionnalit\u00e9s n\u00e9cessaires dans nos onduleurs \u00e0 chaque fois que possible. Ainsi, le logiciel SMA ShadeFix et <a href=\"https:\/\/www.sma.de\/fr\/produits\/surveillance-controle\/sma-smart-connected.html\" target=\"_blank\" rel=\"noopener noreferrer\">la fonction de maintenance et surveillance SMA Smart Connected<\/a> permettent d\u2019optimiser la production \u00e9nerg\u00e9tique tout au long de la dur\u00e9e de vie du syst\u00e8me PV. SMA Smart Connected v\u00e9rifie en permanence le statut des onduleurs, alerte les installateurs en cas de probl\u00e8me et envoie des conseils de r\u00e9paration, voire demande un appareil de remplacement automatiquement. Cela permet de r\u00e9duire les d\u00e9placements.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Que se passe-t-il si l\u2019installateur ou l\u2019utilisateur du syst\u00e8me PV a d\u00e9j\u00e0 opt\u00e9 pour des optimiseurs\u202f? <\/strong><\/p>\n<p>Ce n\u2019est financi\u00e8rement pas raisonnable de les retirer d\u2019un syst\u00e8me existant. Cela demanderait aux installateurs de retourner sur le toit et investir du temps et du capital risque. Apr\u00e8s tout, c\u2019est l\u2019utilisateur qui supporte les co\u00fbts. Toutefois, si les optimiseurs sont sur le point d\u2019\u00eatre remplac\u00e9s, moderniser le syst\u00e8me avec une technologie d\u2019onduleur plus avanc\u00e9e serait une bonne alternative.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Quels seraient vos conseils pour les utilisateurs de syst\u00e8mes PV ou ceux qui souhaitent en acqu\u00e9rir un\u202f? <\/strong><\/p>\n<p>Il est essentiel d\u2019\u00eatre bien conseill\u00e9 et inform\u00e9 en amont. Ne vous inqui\u00e9tez pas pour un peu d\u2019ombrage.<\/p>\n<p>&nbsp;<\/p>\n<p>*L\u2019Alliance SunSpec est une organisation commerciale regroupant plus de 100 acteurs de l\u2019industrie de l\u2019\u00e9nergie solaire et du stockage d\u2019Am\u00e9rique du Nord, d\u2019Europe et d\u2019Asie. Elle a pour but d\u2019\u00e9tablir des normes standard pour l\u2019interop\u00e9rabilit\u00e9 des syst\u00e8mes \u00ab\u202fplug and play\u202f\u00bb.<\/p>\n<div  class='av_promobox av-av_promobox-6bdac236d5de4b527c724c6f30d180fb avia-button-no  avia-builder-el-0  el_before_av_button  avia-builder-el-first '><div class='avia-promocontent'><p><div  class='flex_column av-av_one_half-2a9015ff38129c418a3f2eafba3e9512 av_one_half  avia-builder-el-1  el_before_av_one_half  avia-builder-el-first  first flex_column_div  '     ><h2>\u00c0 propos d\u2019Hannes<\/h2>\n<p>En tant qu\u2019Expert en technologies d\u2019onduleurs strings, Hannes travaille sur des solutions d\u2019optimisation de la production d\u2019installations PV et leur int\u00e9gration dans les onduleurs SMA. Ing\u00e9nieur dipl\u00f4m\u00e9 en informatique et \u00e9lectrotechnique, il appr\u00e9cie l\u2019exp\u00e9rience internationale et la vision globale des sujets de s\u00e9curit\u00e9 concernant l&rsquo;utilisation des technologies solaires.<\/p><\/div><br \/>\n<div  class='flex_column av-av_one_half-e8b5fe92f046e7242c54fd1caeab6ce2 av_one_half  avia-builder-el-2  el_after_av_one_half  avia-builder-el-last  flex_column_div  '     ><p><a href=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf.png\"><img decoding=\"async\" class=\"wp-image-110972 aligncenter lazyload\" data-src=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf-262x265.png\" alt=\"\" width=\"180\" height=\"182\" data-srcset=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf-262x265.png 262w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf-75x75.png 75w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf-36x36.png 36w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf-120x120.png 120w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf-450x456.png 450w, https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/Hannes-Knopf.png 536w\" data-sizes=\"(max-width: 180px) 100vw, 180px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 180px; --smush-placeholder-aspect-ratio: 180\/182;\" \/><\/a><\/p>\n<div  class='avia-icon-list-container av-av_iconlist-b9622264be8b33ecf932b804b1272287  avia-builder-el-3  avia-builder-el-no-sibling '><ul class='avia-icon-list avia_animate_when_almost_visible avia-icon-list-left av-iconlist-big av-av_iconlist-b9622264be8b33ecf932b804b1272287 avia-iconlist-animate'><li><a href='https:\/\/www.linkedin.com\/in\/hannes-knopf-0326772b\/' title='&lt;span lang=&quot;EN-US&quot;&gt;Hannes sur LinkedIn&lt;\/span&gt;' target=\"_blank\" rel=\"noopener noreferrer\" class='iconlist_icon av-av_iconlist_item-b748d316ce68cb623c472f6900e7dc7f avia-font-entypo-fontello'><span class='iconlist-char' aria-hidden='true' data-av_icon='\ue8fc' data-av_iconfont='entypo-fontello'><\/span><\/a><article class=\"article-icon-entry av-iconlist-empty\"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class=\"iconlist_content_wrap\"><header class=\"entry-content-header\"><h4 class='av_iconlist_title iconlist_title  '  itemprop=\"headline\" ><a href='https:\/\/www.linkedin.com\/in\/hannes-knopf-0326772b\/' title='&lt;span lang=&quot;EN-US&quot;&gt;Hannes sur LinkedIn&lt;\/span&gt;' target=\"_blank\" rel=\"noopener noreferrer\"><span lang=\"EN-US\">Hannes sur LinkedIn<\/span><\/a><\/h4><\/header><div class='iconlist_content '  itemprop=\"text\" ><\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><div class=\"iconlist-timeline\"><\/div><\/li>\n<\/ul><\/div><\/div><\/p>\n<\/div><\/div>\n<p>Vous souhaitez en savoir plus sur la comparaison entre SMA ShadeFix et les optimiseurs?<\/p>\n<div  class='avia-button-wrap av-av_button-8816190958d3b8e5c97079f3b88f327e-wrap avia-button-left  avia-builder-el-4  el_after_av_promobox  avia-builder-el-last '>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-av_button-8816190958d3b8e5c97079f3b88f327e\">\n#top #wrap_all .avia-button.av-av_button-8816190958d3b8e5c97079f3b88f327e{\nbackground-color:#e2001a;\nborder-color:#e2001a;\ncolor:#ffffff;\ntransition:all 0.4s ease-in-out;\n}\n<\/style>\n<a href='https:\/\/www.sma.de\/fr\/shadefix\/telechargez-le-livre-blanc.html' class='avia-button av-av_button-8816190958d3b8e5c97079f3b88f327e av-link-btn avia-icon_select-no avia-size-large avia-position-left' target=\"_blank\" rel=\"noopener noreferrer\"><span class='avia_iconbox_title' >T\u00e9l\u00e9chargez le livre blanc <\/span><\/a><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;111297&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;10&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.1&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;1&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;4.1\\\/5 - (10 votes)&quot;,&quot;size&quot;:&quot;22&quot;,&quot;title&quot;:&quot;Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f&quot;,&quot;width&quot;:&quot;93.8&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 93.8px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 1px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 22px; height: 22px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 17.6px;\">\n            4.1\/5 - (10 votes)    <\/div>\n    <\/div>\n<div class='printomatic pom-default ' id='id8531'  data-print_target='article'><\/div>","protected":false},"excerpt":{"rendered":"<p>Optimiser la production \u00e9nerg\u00e9tique des modules PV de mani\u00e8re intelligente et s\u00fbre \u00e0 la fois. Ajout de composants \u00e9lectroniques ou solution int\u00e9gr\u00e9e\u202f? En quoi les optimiseurs de modules peuvent constituer un risque pour la s\u00e9curit\u00e9\u202f? Et comment les op\u00e9rateurs et les installateurs peuvent-ils b\u00e9n\u00e9ficier d\u2019une efficacit\u00e9 et d\u2019une s\u00e9curit\u00e9 accrues gr\u00e2ce au logiciel int\u00e9gr\u00e9 SMA ShadeFix\u202f? Hannes Knopf, Expert en technologies d\u2019onduleurs strings, partage ses connaissances sur le sujet. <\/p>\n","protected":false},"author":20,"featured_media":110908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[37],"tags":[1175,1162,1161,1176],"class_list":["post-111297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-company","tag-durabilite","tag-mlpe","tag-optimiseur","tag-sma-shadefix-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f - Sunny. SMA Corporate Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f - Sunny. SMA Corporate Blog\" \/>\n<meta property=\"og:description\" content=\"Optimiser la production \u00e9nerg\u00e9tique des modules PV de mani\u00e8re intelligente et s\u00fbre \u00e0 la fois. Ajout de composants \u00e9lectroniques ou solution int\u00e9gr\u00e9e\u202f? En quoi les optimiseurs de modules peuvent constituer un risque pour la s\u00e9curit\u00e9\u202f? Et comment les op\u00e9rateurs et les installateurs peuvent-ils b\u00e9n\u00e9ficier d\u2019une efficacit\u00e9 et d\u2019une s\u00e9curit\u00e9 accrues gr\u00e2ce au logiciel int\u00e9gr\u00e9 SMA ShadeFix\u202f? Hannes Knopf, Expert en technologies d\u2019onduleurs strings, partage ses connaissances sur le sujet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunny. SMA Corporate Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/SMASolarTechnology\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-07T12:45:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-07T07:13:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Anke Baars\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:site\" content=\"@SMAsolar\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Anke Baars\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/\",\"name\":\"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f - Sunny. SMA Corporate Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg\",\"datePublished\":\"2020-05-07T12:45:16+00:00\",\"dateModified\":\"2021-06-07T07:13:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/0f1d8b768c8973041255945639a8f9b4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#primaryimage\",\"url\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg\",\"contentUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg\",\"width\":1400,\"height\":676,\"caption\":\"Hannes Knopf, Expert in Modern String Inverter Features Interview\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.sma-sunny.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#website\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/\",\"name\":\"Sunny. SMA Corporate Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sma-sunny.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/0f1d8b768c8973041255945639a8f9b4\",\"name\":\"Anke Baars\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2018\/02\/anke-avatar.jpg\",\"contentUrl\":\"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2018\/02\/anke-avatar.jpg\",\"caption\":\"Anke Baars\"},\"description\":\"Copy Editor for SMA DACH region\",\"url\":\"https:\/\/www.sma-sunny.com\/fr\/author\/anke\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f - Sunny. SMA Corporate Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/","og_locale":"fr_FR","og_type":"article","og_title":"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f - Sunny. SMA Corporate Blog","og_description":"Optimiser la production \u00e9nerg\u00e9tique des modules PV de mani\u00e8re intelligente et s\u00fbre \u00e0 la fois. Ajout de composants \u00e9lectroniques ou solution int\u00e9gr\u00e9e\u202f? En quoi les optimiseurs de modules peuvent constituer un risque pour la s\u00e9curit\u00e9\u202f? Et comment les op\u00e9rateurs et les installateurs peuvent-ils b\u00e9n\u00e9ficier d\u2019une efficacit\u00e9 et d\u2019une s\u00e9curit\u00e9 accrues gr\u00e2ce au logiciel int\u00e9gr\u00e9 SMA ShadeFix\u202f? Hannes Knopf, Expert en technologies d\u2019onduleurs strings, partage ses connaissances sur le sujet.","og_url":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/","og_site_name":"Sunny. SMA Corporate Blog","article_publisher":"https:\/\/facebook.com\/SMASolarTechnology","article_published_time":"2020-05-07T12:45:16+00:00","article_modified_time":"2021-06-07T07:13:10+00:00","og_image":[{"width":1400,"height":676,"url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg","type":"image\/jpeg"}],"author":"Anke Baars","twitter_card":"summary_large_image","twitter_creator":"@SMAsolar","twitter_site":"@SMAsolar","twitter_misc":{"\u00c9crit par":"Anke Baars","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/","url":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/","name":"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f - Sunny. SMA Corporate Blog","isPartOf":{"@id":"https:\/\/www.sma-sunny.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#primaryimage"},"image":{"@id":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg","datePublished":"2020-05-07T12:45:16+00:00","dateModified":"2021-06-07T07:13:10+00:00","author":{"@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/0f1d8b768c8973041255945639a8f9b4"},"breadcrumb":{"@id":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#primaryimage","url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg","contentUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2020\/05\/2020-05-06-expert-chat-knopf_1400x676.jpg","width":1400,"height":676,"caption":"Hannes Knopf, Expert in Modern String Inverter Features Interview"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sma-sunny.com\/fr\/pv-moduloptimierer-optimiseurs-de-modules-pv%e2%80%af-aussi-utiles-quun-frigo-au-pole-nord-%e2%80%afso-ueberfluessig-wie-kuehlschraenke-am-nordpol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sma-sunny.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Optimiseurs de modules PV\u202f: aussi utiles qu\u2019un frigo au p\u00f4le Nord.\u202f"}]},{"@type":"WebSite","@id":"https:\/\/www.sma-sunny.com\/fr\/#website","url":"https:\/\/www.sma-sunny.com\/fr\/","name":"Sunny. SMA Corporate Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sma-sunny.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/0f1d8b768c8973041255945639a8f9b4","name":"Anke Baars","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sma-sunny.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2018\/02\/anke-avatar.jpg","contentUrl":"https:\/\/www.sma-sunny.com\/wp-content\/uploads\/2018\/02\/anke-avatar.jpg","caption":"Anke Baars"},"description":"Copy Editor for SMA DACH region","url":"https:\/\/www.sma-sunny.com\/fr\/author\/anke\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts\/111297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/comments?post=111297"}],"version-history":[{"count":0,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/posts\/111297\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/media\/110908"}],"wp:attachment":[{"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/media?parent=111297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/categories?post=111297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sma-sunny.com\/fr\/wp-json\/wp\/v2\/tags?post=111297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}